{"id":76951,"date":"2026-05-10T16:10:31","date_gmt":"2026-05-10T16:10:31","guid":{"rendered":"https:\/\/www.camper.is\/festival-del-solstizio-segreto-di-reykjavik-15-18-giugno-allestimento-scenico\/"},"modified":"2026-05-10T16:10:31","modified_gmt":"2026-05-10T16:10:31","slug":"festival-del-solstizio-segreto-di-reykjavik-15-18-giugno-allestimento-scenico","status":"publish","type":"post","link":"https:\/\/www.camper.is\/it\/festival-del-solstizio-segreto-di-reykjavik-15-18-giugno-allestimento-scenico\/","title":{"rendered":"Festival del Solstizio Segreto di Reykjavik (15-18 giugno), allestimento scenico"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-3377\" src=\"https:\/\/www.camper.is\/wp-content\/uploads\/2017\/06\/Bildschirmfoto-2017-06-14-um-12.16.29-300x165.png\" alt=\"\" width=\"300\" height=\"165\" title=\"\" srcset=\"https:\/\/www.camper.is\/wp-content\/uploads\/2017\/06\/Bildschirmfoto-2017-06-14-um-12.16.29-300x165.png 300w, https:\/\/www.camper.is\/wp-content\/uploads\/2017\/06\/Bildschirmfoto-2017-06-14-um-12.16.29-768x422.png 768w, https:\/\/www.camper.is\/wp-content\/uploads\/2017\/06\/Bildschirmfoto-2017-06-14-um-12.16.29-1024x562.png 1024w, https:\/\/www.camper.is\/wp-content\/uploads\/2017\/06\/Bildschirmfoto-2017-06-14-um-12.16.29.png 1206w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Il grande palco \u00e8 stato allestito al Secret Solstice, il festival musicale che si terr\u00e0 nella valle di Laugardalur a Reykjav\u00edk questo fine settimana. <em><a href=\"http:\/\/www.mbl.is\/folk\/frettir\/2017\/06\/12\/staersta_svidid_til_thessa_komid_upp\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">mbl.is<\/a><\/em>. Secondo gli organizzatori, si tratta del palco pi\u00f9 grande mai allestito in Islanda. <\/p>\n<p>Il festival musicale, che si terr\u00e0 per la quarta volta, inizier\u00e0 questo gioved\u00ec e proseguir\u00e0 fino a domenica. Secondo il <a href=\"http:\/\/secretsolstice.is\/wp-content\/uploads\/2017\/06\/SS17_Scheduel_web.pdf\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">programma<\/a> del festival, gli headliner che saliranno sul palco principale sono l&#8217;artista statunitense Chaka Khan gioved\u00ec, il gruppo rock statunitense Foo Fighters venerd\u00ec, il gruppo britannico The Prodigy sabato e il rapper statunitense Rick Ross domenica. <\/p>\n<p>Tra gli artisti locali figurano \u00de\u00f3runn Anton\u00eda Magn\u00fasd\u00f3ttir, che \u00e8 anche una delle organizzatrici del festival, Hildur, \u00dalfur \u00dalfur, Amabadama, Emmsj\u00e9 Gauti, GKR e Aron Can. Da\u00f0i Freyr, che si \u00e8 fatto conoscere di recente come secondo classificato alle qualificazioni islandesi per l&#8217;Eurovision, si esibir\u00e0 sul palco di Gimli domenica sera. <\/p>\n<p>La disposizione del sito del festival \u00e8 cambiata notevolmente rispetto all&#8217;anno scorso e l&#8217;ingresso principale si trova ora all&#8217;estremit\u00e0 meridionale del vicino stadio nazionale Laugardalsv\u00f6llur. Sveinn R\u00fan Einarsson, uno degli organizzatori del festival, afferma che questo fa una grande differenza ed \u00e8 stato uno dei fattori che ha permesso di allestire il palco pi\u00f9 grande mai realizzato in Islanda. <\/p>\n<p>Il sito \u00e8 stato ampliato di 5.000 m2 e gli organizzatori si aspettano fino a 20.000 ospiti durante il festival. L&#8217;anno scorso gli ospiti stranieri sono stati 8.500 e Sveinn ha dichiarato di aspettarsi un numero simile quest&#8217;anno. <\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Il grande palco \u00e8 stato allestito al Secret Solstice, il festival musicale che si terr\u00e0 nella valle di Laugardalur a Reykjav\u00edk questo fine settimana. mbl.is. Secondo gli organizzatori, si tratta del palco pi\u00f9 grande mai allestito in Islanda. Il festival musicale, che si terr\u00e0 per la quarta volta, inizier\u00e0 questo gioved\u00ec e proseguir\u00e0 fino [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1891],"tags":[],"class_list":["post-76951","post","type-post","status-publish","format-standard","hentry","category-blog-di-notizie-e-viaggi"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/comments?post=76951"}],"version-history":[{"count":0,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76951\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/media?parent=76951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/categories?post=76951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/tags?post=76951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}