{"id":76814,"date":"2026-05-10T16:08:56","date_gmt":"2026-05-10T16:08:56","guid":{"rendered":"https:\/\/www.camper.is\/domanda-6-avvento-competizione\/"},"modified":"2026-05-10T16:08:56","modified_gmt":"2026-05-10T16:08:56","slug":"domanda-6-avvento-competizione","status":"publish","type":"post","link":"https:\/\/www.camper.is\/it\/domanda-6-avvento-competizione\/","title":{"rendered":"Domanda 6 Avvento - Competizione"},"content":{"rendered":"<p class=\"p1\"><span style=\"font-size: 14pt;\">Qual \u00e8 la capitale dell&#8217;Islanda?<\/span><\/p>\n<p><a href=\"https:\/\/www.iceland.ch\/wp-content\/uploads\/2017\/11\/reykjavik-Iceland.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-3056 size-medium\" src=\"https:\/\/www.iceland.ch\/wp-content\/uploads\/2017\/11\/reykjavik-Iceland-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" title=\"\"><\/a><\/p>\n<p class=\"p1\"><span class=\"s1\" style=\"font-size: 14pt;\"><span style=\"font-size: 36pt;\"><span style=\"font-size: 24pt;\"><span style=\"font-size: 36pt;\">_ _ _ _ _ _ _ _ _ <\/span> <\/span><\/span><\/span><span class=\"s1\" style=\"font-size: 14pt;\"><span style=\"font-size: 36pt;\"><span style=\"font-size: 12pt;\">(9 lettere)<\/span>     <\/span><\/span> <\/p>\n<p>Raccogli la prima lettera di ciascuna delle 24 risposte fino al 24 dicembre e inviaci la frase risolutiva.<\/p>\n<p>Ulteriori informazioni sul Concorso sono disponibili qui:<\/p>\n<p><a href=\"https:\/\/www.campericeland.is\/en\/3-2-1-go\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Avvento - Concorso<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Qual \u00e8 la capitale dell&#8217;Islanda? _ _ _ _ _ _ _ _ _ (9 lettere) Raccogli la prima lettera di ciascuna delle 24 risposte fino al 24 dicembre e inviaci la frase risolutiva. Ulteriori informazioni sul Concorso sono disponibili qui: Avvento - Concorso &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1891],"tags":[],"class_list":["post-76814","post","type-post","status-publish","format-standard","hentry","category-blog-di-notizie-e-viaggi"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/comments?post=76814"}],"version-history":[{"count":0,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76814\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/media?parent=76814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/categories?post=76814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/tags?post=76814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}