{"id":76703,"date":"2026-05-10T16:07:01","date_gmt":"2026-05-10T16:07:01","guid":{"rendered":"https:\/\/www.camper.is\/promemoria-reykjavik-proiettera-la-coppa-del-mondo-allaperto\/"},"modified":"2026-05-10T16:07:01","modified_gmt":"2026-05-10T16:07:01","slug":"promemoria-reykjavik-proiettera-la-coppa-del-mondo-allaperto","status":"publish","type":"post","link":"https:\/\/www.camper.is\/it\/promemoria-reykjavik-proiettera-la-coppa-del-mondo-allaperto\/","title":{"rendered":"Promemoria: Reykjav\u00edk proietter\u00e0 la Coppa del Mondo all&#8217;aperto"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Le aree di proiezione sono un progetto di collaborazione tra la citt\u00e0 di Reykjav\u00edk e la Federazione calcistica dell&#8217;Islanda (KS\u00cd). Nel 2016 \u00e8 stata allestita un&#8217;area di proiezione all&#8217;aperto ad Arnarh\u00f3ll per le partite dell&#8217;Islanda nei campionati UEFA. Quest&#8217;anno la citt\u00e0 ha deciso di spostare le proiezioni a Hlj\u00f3msk\u00e1lagar\u00f0ur per accogliere una folla pi\u00f9 numerosa e fornire servizi migliori.  <\/p>\n<p>Oltre a un grande schermo e a un palcoscenico, il progetto dell&#8217;area prevede sei stand gastronomici, servizi igienici e quattro aree gioco per i bambini.<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Le aree di proiezione sono un progetto di collaborazione tra la citt\u00e0 di Reykjav\u00edk e la Federazione calcistica dell&#8217;Islanda (KS\u00cd). Nel 2016 \u00e8 stata allestita un&#8217;area di proiezione all&#8217;aperto ad Arnarh\u00f3ll per le partite dell&#8217;Islanda nei campionati UEFA. Quest&#8217;anno la citt\u00e0 ha deciso di spostare le proiezioni a Hlj\u00f3msk\u00e1lagar\u00f0ur per accogliere una folla pi\u00f9 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1891],"tags":[],"class_list":["post-76703","post","type-post","status-publish","format-standard","hentry","category-blog-di-notizie-e-viaggi"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/comments?post=76703"}],"version-history":[{"count":0,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76703\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/media?parent=76703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/categories?post=76703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/tags?post=76703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}