{"id":76694,"date":"2026-05-10T16:06:57","date_gmt":"2026-05-10T16:06:57","guid":{"rendered":"https:\/\/www.camper.is\/vacanze-verslunarmannahelgi-weekend-dei-mercanti-ad-agosto-2018-orari-di-apertura-vin-budin\/"},"modified":"2026-05-10T16:06:57","modified_gmt":"2026-05-10T16:06:57","slug":"vacanze-verslunarmannahelgi-weekend-dei-mercanti-ad-agosto-2018-orari-di-apertura-vin-budin","status":"publish","type":"post","link":"https:\/\/www.camper.is\/it\/vacanze-verslunarmannahelgi-weekend-dei-mercanti-ad-agosto-2018-orari-di-apertura-vin-budin\/","title":{"rendered":"Vacanze: Verslunarmannahelgi (Weekend dei Mercanti) ad agosto 2018 - orari di apertura Vin Budin"},"content":{"rendered":"<header>\n<h1 class=\"node-title\">Gli islandesi fanno scorta di alcolici per il weekend dei commercianti<\/h1>\n<p>Negozi di liquori islandesi&nbsp;<a href=\"https:\/\/www.vinbudin.is\/heim\/um_atvr\/frettir\/frettir-artal\/frettir-nanar\/verslunarmannahelgin2018.aspx\" target=\"_blank\" rel=\"nofollow noopener\">ha venduto 767.000 litri<\/a> di alcolici l&#8217;anno scorso nella settimana che precede il Verslunarmannahelgi (Weekend dei Mercanti), un lungo fine settimana che si celebra all&#8217;inizio di agosto in Islanda. Circa 137.000 clienti sono entrati nei negozi di alcolici durante la settimana, quasi 30.000 in pi\u00f9 rispetto alla media settimanale di luglio. La popolazione islandese, per fare un confronto, \u00e8 di 350.000 abitanti.  &nbsp;<a href=\"http:\/\/www.ruv.is\/frett\/buast-ma-vid-ad-um-800-thusund-litrar-seljist\" target=\"_blank\" rel=\"nofollow noopener\">R\u00daV<\/a> ha riferito per prima.<\/p>\n<p>Il Weekend dei Mercanti \u00e8 il momento culminante dell&#8217;estate per molti islandesi: molti abitanti della capitale lasciano la casa per andare in campagna, spesso per partecipare a uno dei tanti festival all&#8217;aperto che si svolgono in tutto il paese.<\/p>\n<p>V\u00ednb\u00fa\u00f0in, l&#8217;azienda di Stato per gli alcolici e il tabacco dell&#8217;Islanda, ha dichiarato che tutte le indicazioni indicano che le vendite di quest&#8217;anno saranno altrettanto elevate di quelle dell&#8217;anno scorso. Nel 2017, il volume pi\u00f9 alto di clienti \u00e8 stato registrato il venerd\u00ec, quando sono stati venduti 230.000 litri di alcolici. La maggior parte dei clienti quel giorno ha fatto acquisti tra le 16 e le 18, a un ritmo di circa 6.400 clienti all&#8217;ora.  <\/p>\n<p>Per gli abitanti e i viaggiatori, pu\u00f2 essere utile sapere che i negozi di V\u00ednb\u00fa\u00f0in saranno chiusi luned\u00ec 6 agosto per la Giornata dei Mercanti. Negozio di liquori &nbsp;<a href=\"https:\/\/www.vinbudin.is\/english\/home\/opnunartimar.aspx\" target=\"_blank\" rel=\"nofollow noopener\">Gli orari di apertura<\/a> possono essere consultati sul sito web di V\u00ednb\u00fa\u00f0in.<\/p>\n<\/header>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Gli islandesi fanno scorta di alcolici per il weekend dei commercianti Negozi di liquori islandesi&nbsp;ha venduto 767.000 litri di alcolici l&#8217;anno scorso nella settimana che precede il Verslunarmannahelgi (Weekend dei Mercanti), un lungo fine settimana che si celebra all&#8217;inizio di agosto in Islanda. Circa 137.000 clienti sono entrati nei negozi di alcolici durante la settimana, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1891],"tags":[],"class_list":["post-76694","post","type-post","status-publish","format-standard","hentry","category-blog-di-notizie-e-viaggi"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/comments?post=76694"}],"version-history":[{"count":0,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76694\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/media?parent=76694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/categories?post=76694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/tags?post=76694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}