{"id":76690,"date":"2026-05-10T16:06:52","date_gmt":"2026-05-10T16:06:52","guid":{"rendered":"https:\/\/www.camper.is\/eclissi-solare-visibile-sabato-dallislanda\/"},"modified":"2026-05-10T16:06:52","modified_gmt":"2026-05-10T16:06:52","slug":"eclissi-solare-visibile-sabato-dallislanda","status":"publish","type":"post","link":"https:\/\/www.camper.is\/it\/eclissi-solare-visibile-sabato-dallislanda\/","title":{"rendered":"Eclissi solare visibile sabato dall&#8217;Islanda"},"content":{"rendered":"<p>Un&#8217;eclissi solare parziale sar\u00e0 visibile dall&#8217;Islanda l&#8217;11 agosto.<\/p>\n<p>Un&#8217;eclissi solare parziale sar\u00e0 visibile dall&#8217;Islanda questo sabato 11 agosto,&nbsp;<a href=\"http:\/\/www.ruv.is\/frett\/solmyrkvi-sjaanlegur-fra-islandi\" target=\"_blank\" rel=\"nofollow noopener\">R\u00daV<\/a> riporta. L&#8217;eclissi dovrebbe essere visibile da tutte le parti del paese se il tempo lo permette. <\/p>\n<p>Sito web di astronomia&nbsp;<a href=\"https:\/\/www.stjornufraedi.is\/frettir\/solmyrkvi-11-agust-2018\" target=\"_blank\" rel=\"nofollow noopener\">Stj\u00f3rnufr\u00e6\u00f0ivefurinn<\/a> fornisce ulteriori dettagli sull&#8217;eclissi, che sar\u00e0 visibile tra le 8.10 e le 9.26, con lievi variazioni in tutto il paese. A seconda della posizione dell&#8217;osservatore, la luna bloccher\u00e0 da poco meno del 9% (Isole Westman) a ben il 14% (\u00cdsafj\u00f6r\u00f0ur) della superficie visibile del sole. <\/p>\n<p>L&#8217;eclissi di sabato sar\u00e0 visibile soprattutto a nord e a sud del circolo polare artico, oppure dal Canada nord-orientale, dalla Groenlandia, dall&#8217;Islanda, dall&#8217;Europa settentrionale e dall&#8217;Asia settentrionale.<\/p>\n<p>L&#8217;ultima eclissi solare visibile dall&#8217;Islanda si \u00e8 verificata il 21 agosto 2017. La prossima avr\u00e0 luogo tra tre anni, il 10 giugno 2021. <\/p>\n<p>Si ricorda agli osservatori che per osservare l&#8217;eclissi parziale sono necessari occhiali protettivi o un telescopio con filtro solare. I normali occhiali da sole non sono sufficienti. <\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Un&#8217;eclissi solare parziale sar\u00e0 visibile dall&#8217;Islanda l&#8217;11 agosto. Un&#8217;eclissi solare parziale sar\u00e0 visibile dall&#8217;Islanda questo sabato 11 agosto,&nbsp;R\u00daV riporta. L&#8217;eclissi dovrebbe essere visibile da tutte le parti del paese se il tempo lo permette. Sito web di astronomia&nbsp;Stj\u00f3rnufr\u00e6\u00f0ivefurinn fornisce ulteriori dettagli sull&#8217;eclissi, che sar\u00e0 visibile tra le 8.10 e le 9.26, con lievi variazioni in [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1891],"tags":[],"class_list":["post-76690","post","type-post","status-publish","format-standard","hentry","category-blog-di-notizie-e-viaggi"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/comments?post=76690"}],"version-history":[{"count":0,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76690\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/media?parent=76690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/categories?post=76690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/tags?post=76690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}