{"id":76687,"date":"2026-05-10T16:06:51","date_gmt":"2026-05-10T16:06:51","guid":{"rendered":"https:\/\/www.camper.is\/la-route-1-e-parzialmente-chiusa-a-causa-dellalluvione-glaciale-di-skafta\/"},"modified":"2026-05-10T16:06:51","modified_gmt":"2026-05-10T16:06:51","slug":"la-route-1-e-parzialmente-chiusa-a-causa-dellalluvione-glaciale-di-skafta","status":"publish","type":"post","link":"https:\/\/www.camper.is\/it\/la-route-1-e-parzialmente-chiusa-a-causa-dellalluvione-glaciale-di-skafta\/","title":{"rendered":"La Route 1 \u00e8 parzialmente chiusa a causa dell&#8217;alluvione glaciale di Skaft\u00e1"},"content":{"rendered":"<div class=\"field-body\">\n<p>La strada 1, a ovest di Kirkjub\u00e6jarklaustur, \u00e8 stata chiusa a causa di un&#8217;inondazione causata dalla piena glaciale del fiume Skaft\u00e1,&nbsp;<a href=\"http:\/\/www.visir.is\/g\/2018180809440\/thjodvegi-1-um-eldhraun-lokad-vegna-vatns-ur-skaftar-hlaupi\" rel=\"nofollow noopener\" target=\"_blank\">V\u00edsir riporta<\/a>. La polizia dell&#8217;Islanda meridionale ha segnalato la situazione e il Met Office islandese ha emesso un avviso di viaggio generale il 3 giugno. <\/p>\n<p>\u00c1g\u00fast Freyr Bjartmarsson, caposquadra dell&#8217;Amministrazione stradale e costiera islandese, ha dichiarato che l&#8217;acqua \u00e8 ora troppo profonda per il passaggio delle auto, ma che non si pu\u00f2 dire con certezza quando il livello dell&#8217;acqua regredir\u00e0.<\/p>\n<p>\u00c8 stato aperto un percorso di bypass attraverso Me\u00f0allandsvegur, che dovrebbe rallentare i viaggiatori di circa 40-60 minuti in totale.<\/p>\n<p>L&#8217;inondazione glaciale ha gi\u00e0 raggiunto un punto massimo e si prevede che ora regredir\u00e0 lentamente, secondo il Met Office islandese. Gli effetti dell&#8217;alluvione si faranno sentire nei prossimi giorni e si prevede che Skaft\u00e1 non avr\u00e0 un flusso d&#8217;acqua regolare fino alla fine della settimana. <\/p>\n<p>Il fatto che entrambi i calderoni del ghiacciaio Skaft\u00e1rj\u00f6kull si siano allagati contemporaneamente \u00e8 un evento storico, dato che fino a questo momento si era attivato solo un calderone alla volta,&nbsp;<a href=\"http:\/\/www.visir.is\/g\/2018180809474\/sogulegt-ad-badir-katlar-skaftarjokuls-hlaupi\" rel=\"nofollow noopener\" target=\"_blank\">V\u00edsir riporta.<\/a><\/p>\n<p>\u00c8 stata segnalata una puzza di zolfo nella regione, ma l&#8217;odore pu\u00f2 essere avvertito a grande distanza. L&#8217;ultima volta che si \u00e8 verificata un&#8217;inondazione glaciale a Skaft\u00e1, nel 2015, \u00e8 stata segnalata la presenza di zolfo nell&#8217;aria in Norvegia. <\/p>\n<p><em>Si consiglia ai viaggiatori di visitare il sito web della Icelandic Road and Coastal Administration per ulteriori informazioni, <a href=\"http:\/\/www.road.is\/\" rel=\"nofollow noopener\" target=\"_blank\">www.road.is,<\/a> o di contattarli telefonicamente al numero 1777.<\/em><\/p>\n<\/div>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>La strada 1, a ovest di Kirkjub\u00e6jarklaustur, \u00e8 stata chiusa a causa di un&#8217;inondazione causata dalla piena glaciale del fiume Skaft\u00e1,&nbsp;V\u00edsir riporta. La polizia dell&#8217;Islanda meridionale ha segnalato la situazione e il Met Office islandese ha emesso un avviso di viaggio generale il 3 giugno. \u00c1g\u00fast Freyr Bjartmarsson, caposquadra dell&#8217;Amministrazione stradale e costiera islandese, ha [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1891],"tags":[],"class_list":["post-76687","post","type-post","status-publish","format-standard","hentry","category-blog-di-notizie-e-viaggi"],"acf":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/comments?post=76687"}],"version-history":[{"count":0,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/posts\/76687\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/media?parent=76687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/categories?post=76687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.camper.is\/it\/wp-json\/wp\/v2\/tags?post=76687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}