{"id":31556,"date":"2019-11-17T13:48:01","date_gmt":"2019-11-17T13:48:01","guid":{"rendered":"https:\/\/www.campericeland.is\/sobre-nosotros\/"},"modified":"2026-07-19T16:38:47","modified_gmt":"2026-07-19T16:38:47","slug":"sobre-nosotros","status":"publish","type":"page","link":"https:\/\/www.camper.is\/es\/vegvisir-wayfinder-para-viajeros\/sobre-nosotros\/","title":{"rendered":"Sobre nosotros"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section section_has_divider et_pb_bottom_divider\">\n<div class=\"et_pb_row_0 et_pb_row et_block_row\">\n<div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_dark et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h1>Camper Islandia<br \/><a href=\"mailto:info@camper.is\"><\/a><\/h1>\n<h1><\/h1>\n<p>&nbsp;<\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 14px; top: 125.188px;\">\n<div class=\"gtx-trans-icon\"> <\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_1 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_1 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_code_0 et_pb_code et_pb_module\"><div class=\"et_pb_code_inner\"><div class=\"camper-whatsapp-responsive-box\" style=\"box-sizing: border-box; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Arial, sans-serif; background-color: #0f172a; border: 1px solid #1e293b; border-left: 4px solid #10b981; border-radius: 12px; padding: 25px 30px; margin-bottom: 35px; box-shadow: 0 4px 20px rgba(0,0,0,0.25); display: flex; flex-wrap: wrap; align-items: center; justify-content: space-between; gap: 25px;\">\n    \n    <!-- Left Section: Text Content (Scales dynamically) -->\n    <div style=\"box-sizing: border-box; flex: 1; min-width: 280px;\">\n        <div style=\"display: flex; align-items: center; margin-bottom: 8px;\">\n            <span style=\"font-size: 22px; margin-right: 10px; line-height: 1;\">\ud83d\udcac<\/span>\n            <h3 style=\"color: #ffffff; font-size: 18px; font-weight: bold; margin: 0; letter-spacing: -0.3px;\">\u00bfNecesitas asistencia instant\u00e1nea? Chatea con nosotros por WhatsApp <\/h3>\n        <\/div>\n        <p style=\"color: #94a3b8; font-size: 14px; margin: 0 0 15px 0; line-height: 1.6; max-width: 680px;\">\n  Tanto si est\u00e1s de viaje en Islandia como si est\u00e1s planificando tu pr\u00f3ximo viaje: Escanea el c\u00f3digo QR o haz clic en el enlace directo para iniciar inmediatamente una conversaci\u00f3n con nuestro equipo de asistencia de alquiler.\n        <\/p>\n        <p style=\"color: #ffffff; font-size: 14px; margin: 0; font-weight: 500; word-break: break-all;\">\n  \ud83d\udd17 Enlace directo: <a href=\"https:\/\/wa.me\/message\/STFXPCVUIMXND1\" target=\"_blank\" style=\"color: #10b981; text-decoration: none; font-weight: bold; border-bottom: 1px dashed #10b981; padding-bottom: 1px;\" rel=\"noopener\">wa.me\/message\/STFXPCVUIMXND1 \u2192<\/a>\n        <\/p>\n    <\/div>\n    \n    <!-- Right Section: Large Clickable QR Code (Centers on Mobile) -->\n    <div style=\"box-sizing: border-box; margin: 0 auto; text-align: center; flex-shrink: 0;\">\n        <a href=\"https:\/\/wa.me\/message\/STFXPCVUIMXND1\" target=\"_blank\" style=\"display: inline-block; text-decoration: none; cursor: pointer;\" rel=\"noopener\">\n            <div style=\"background-color: #ffffff; padding: 10px; border-radius: 10px; display: inline-block; box-shadow: 0 4px 14px rgba(0,0,0,0.4); border: 1px solid rgba(16, 185, 129, 0.2);\">\n                <img decoding=\"async\" src=\"https:\/\/www.camper.is\/wp-content\/uploads\/2026\/06\/STFXPCVUIMXND1.png\" alt=\"C\u00f3digo QR de WhatsApp de Camper.is\" width=\"210\" height=\"210\" style=\"display: block; border: 0; max-width: 100%; height: auto;\" title=\"\">\n            <\/div>\n            <div style=\"color: #10b981; font-size: 11px; font-weight: 600; text-align: center; margin-top: 8px; letter-spacing: 0.5px; text-transform: uppercase;\">\n  Haz clic o escanea \ud83d\udcf1\n            <\/div>\n        <\/a>\n    <\/div>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_2 et_pb_row et_block_row\">\n<div class=\"et_pb_column_2 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_0 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/www.camper.is\/wp-content\/uploads\/2026\/03\/CAMPER-ICELAND@2x-150x150.png\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.camper.is\/wp-content\/uploads\/2026\/03\/CAMPER-ICELAND@2x-150x150.png 150w\" class=\"wp-image-75367\" title=\"CAMPER ICELAND@2x\" alt=\"\"><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">ESTACI\u00d3N DE ALQUILER<\/h4><div class=\"et_pb_blurb_description\"><p><strong>CAMPER ISLANDIA Ehf<\/strong><br \/>Klettatr\u00f6\u00f0 15<br \/>IS-262 Keflav\u00edk (Reykjanesb\u00e6r)<br \/>ISLANDIA<\/p>\n<p><a href=\"mailto:info@camper.is\">info@camper.is<\/a><br \/><strong>+354 860 1006 <\/strong> <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_image_0 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img decoding=\"async\" src=\"https:\/\/www.camper.is\/wp-content\/uploads\/2025\/09\/RGB_FF-2024-2025-Eng-White-Horz_Original-scaled.png\" title=\"RGB_FF 2024-2025-Eng-White-Horz_Original\" width=\"2560\" height=\"640\" srcset=\"https:\/\/www.camper.is\/wp-content\/uploads\/2025\/09\/RGB_FF-2024-2025-Eng-White-Horz_Original-scaled.png 2560w, https:\/\/www.camper.is\/wp-content\/uploads\/2025\/09\/RGB_FF-2024-2025-Eng-White-Horz_Original-1280x320.png 1280w, https:\/\/www.camper.is\/wp-content\/uploads\/2025\/09\/RGB_FF-2024-2025-Eng-White-Horz_Original-980x245.png 980w, https:\/\/www.camper.is\/wp-content\/uploads\/2025\/09\/RGB_FF-2024-2025-Eng-White-Horz_Original-480x120.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 2560px, 100vw\" class=\"wp-image-75091\" alt=\"\"><\/span><\/div>\n<\/div>\n\n<div class=\"et_pb_column_3 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_1 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/www.camper.is\/wp-content\/uploads\/2026\/03\/Mjollnir2025color-150x150.png\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.camper.is\/wp-content\/uploads\/2026\/03\/Mjollnir2025color-150x150.png 150w\" class=\"wp-image-75390\" title=\"Mjollnir2025color\" alt=\"\"><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">AGENTE DE VENTAS<\/h4><div class=\"et_pb_blurb_description\"><p>Mjollnir GmbH<br \/>Kantonsstrasse 112<br \/>6234 Triengen<br \/>SUIZA<\/p>\n<p><a href=\"mailto:info@camper.is\">info@camper.is<\/a> <br \/><strong>+41 44 797 99 89<\/strong><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_4 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_2 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap et_pb_only_image_mode_wrap\"><img decoding=\"async\" src=\"https:\/\/www.camper.is\/wp-content\/uploads\/2026\/03\/logo-no-background-150x150.png\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.camper.is\/wp-content\/uploads\/2026\/03\/logo-no-background-150x150.png 150w\" class=\"wp-image-75391\" title=\"logo-no-background\" alt=\"\"><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">CARRETERA DE ISLANDIA<\/h4><div class=\"et_pb_blurb_description\"><p><strong>CAMPER ISLAND Ehf<\/strong><br \/>\nKlettatr\u00f6\u00f0 15<br \/>\nIS-262 Keflav\u00edk (Reykjanesb\u00e6r)<br \/>\nISLAND<\/p>\n<p><a href=\"mailto:info@camper.is\">info@camper.is<\/a><br \/>\n +354<strong> 860 1006<\/strong><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_3 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_5 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone\">\n<section class=\"et_pb_fullwidth_header_0 et_pb_fullwidth_header et_pb_bg_layout_dark et_pb_text_align_left et_pb_module et_flex_module\"><div class=\"et_pb_fullwidth_header_container left\"><div class=\"header-content-container center\"><div class=\"header-content et_flex_module\"><h1 class=\"et_pb_module_header\">\"El m\u00e1s fuerte de Islandia\"<\/h1><div class=\"et_pb_header_content_wrapper\"><p>\"Estamos inmensamente orgullosos de ser reconocidos por Creditinfo como uno de los \"M\u00e1s fuertes de Islandia\", una distinci\u00f3n de \u00e9lite concedida a menos del 2% de las empresas de todo el pa\u00eds. Esta prestigiosa certificaci\u00f3n no es s\u00f3lo una insignia de honor, sino un reflejo de nuestro inquebrantable compromiso con la estabilidad financiera, la transparencia y la excelencia operativa. Para nuestros viajeros, esto significa la tranquilidad absoluta que supone asociarse con un pilar fiable y antiguo del sector tur\u00edstico island\u00e9s. Al mantener a\u00f1o tras a\u00f1o las normas de cr\u00e9dito y rendimiento m\u00e1s estrictas, nos aseguramos de que nuestra flota y nuestros servicios se mantengan al m\u00e1s alto nivel internacional. Cuando reservas a trav\u00e9s de <b data-path-to-node=\"3,0\" data-index-in-node=\"675\">camper.is<\/b> o <b data-path-to-node=\"3,0\" data-index-in-node=\"688\">iceland.ch<\/b>, est\u00e1s eligiendo un socio con la solidez demostrada para respaldar tu viaje de principio a fin\".    <\/p>\n<\/div><div class=\"et_pb_header_button_wrapper\"><a class=\"et_pb_button et_pb_more_button et_pb_button_one\" href=\"https:\/\/www.creditinfo.is\/what-is-strongest-in-iceland\" target=\"_blank\" rel=\"noopener\">Seguir leyendo<\/a><\/div><\/div><\/div><\/div><div class=\"et_pb_fullwidth_header_overlay\"><\/div><div class=\"et_pb_fullwidth_header_scroll\"><\/div><\/section>\n<\/div>\n\n<div class=\"et_pb_column_6 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_12_24_tablet et_flex_column_24_24_phone\">\n<section class=\"et_pb_fullwidth_header_1 et_pb_fullwidth_header et_pb_bg_layout_dark et_pb_text_align_left et_pb_module et_flex_module\"><div class=\"et_pb_fullwidth_header_container left\"><div class=\"header-content-container center\"><div class=\"header-content et_flex_module\"><h1 class=\"et_pb_module_header\">El patrimonio suizo-island\u00e9s<\/h1><div class=\"et_pb_header_content_wrapper\"><p>\"Fundada sobre una fusi\u00f3n \u00fanica de <b data-path-to-node=\"3,0\" data-index-in-node=\"31\">fiabilidad suiza y pasi\u00f3n islandesa<\/b>, Camper Iceland es una empresa familiar pionera desde 1987, cuando abrimos la primera agencia de viajes especializada en Islandia en Suiza. Combinamos los meticulosos est\u00e1ndares de nuestra herencia suiza -centrados en la seguridad, la organizaci\u00f3n y el mantenimiento de alta calidad- con un profundo conocimiento local de los ind\u00f3mitos paisajes de Islandia. Operando tanto a trav\u00e9s de <b data-path-to-node=\"3,0\" data-index-in-node=\"337\">iceland.ch<\/b> como de <b data-path-to-node=\"3,0\" data-index-in-node=\"352\">camper.is<\/b>, tendemos un puente entre las expectativas europeas y las realidades \u00e1rticas. Nuestra misi\u00f3n es proporcionarte la precisi\u00f3n de un reloj suizo y el esp\u00edritu rudo de un explorador island\u00e9s. Tanto si navegas por la Ring Road como por las remotas Tierras Altas, contar\u00e1s con el apoyo de d\u00e9cadas de experiencia internacional y coraz\u00f3n local\".    <\/p>\n<\/div><div class=\"et_pb_header_button_wrapper\"><a class=\"et_pb_button et_pb_more_button et_pb_button_one\" href=\"https:\/\/www.camper.is\/vegvisir-wayfinder-for-travellers\/camper-iceland-the-brand\/\">Haga clic aqu\u00ed<\/a><\/div><\/div><\/div><\/div><div class=\"et_pb_fullwidth_header_overlay\"><\/div><div class=\"et_pb_fullwidth_header_scroll\"><\/div><\/section>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_4 et_pb_row et_block_row\">\n<div class=\"et_pb_column_7 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d7005.920598997663!2d-22.58898250876148!3d63.9607060307733!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x4929fd8fba878545%3A0x34ce608c3b726f21!2sMjollnir%20Camper!5e0!3m2!1sen!2sch!4v1668680917587!5m2!1sen!2sch\" width=\"1200\" height=\"600\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_dark et_animated et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>\"En Camper Iceland, creemos en la transparencia y el juego limpio. Aunque mantenemos una media de 4,3 estrellas, nos enorgullecemos de nuestras honestas evaluaciones de da\u00f1os, que garantizan la seguridad y la calidad de nuestra flota para el pr\u00f3ximo viajero. Te invitamos a leer nuestras respuestas detalladas a los comentarios: defendemos nuestros veh\u00edculos y nuestros est\u00e1ndares de servicio suizo-islandeses.\"<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_5 et_pb_row et-vb-row--no-module et_block_row\">\n<div class=\"et_pb_column_8 et_pb_column et_pb_column_1_2 et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div>\n\n<div class=\"et_pb_column_9 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section section_has_divider et_pb_top_divider\"><div class=\"et_pb_top_inside_divider et-no-transition\"><\/div>\n<div class=\"et_pb_row_6 et_pb_row et_block_row\">\n<div class=\"et_pb_column_10 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>Preguntado con frecuencia<\/h2>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_7 et_pb_row et_block_row\">\n<div class=\"et_pb_column_11 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_3 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">^<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">\u00bfA qu\u00e9 distancia del aeropuerto est\u00e1 la estaci\u00f3n de alquiler?<\/h4><div class=\"et_pb_blurb_description\"><p>Estamos a s\u00f3lo 5 minutos del aeropuerto internacional. El aeropuerto KEF a veces se llama Reykjavik a pesar de que est\u00e1 en Keflavik. Ninguna aerol\u00ednea internacional aterriza en Reikiavik por eso elegimos estar cerca del aeropuerto.  <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_4 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">^<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">\u00bfD\u00f3nde puedo reservar un servicio de traslado a la estaci\u00f3n de alquiler?<\/h4><div class=\"et_pb_blurb_description\"><p>Ofrecemos un servicio de enlace gratuito entre el aeropuerto de Keflav\u00edk (KEF) y los hoteles de la zona. Cuando recojas las maletas o est\u00e9s listo en el vest\u00edbulo de tu hotel, ll\u00e1manos al <b data-path-to-node=\"4,3,0\" data-index-in-node=\"185\">+354 860 1006<\/b>. Para otros lugares (como Reikiavik), te recomendamos que llames a nuestro socio de taxis <b data-path-to-node=\"4,3,0\" data-index-in-node=\"278\">A\u00f0alst\u00f6\u00f0in<\/b> al <b data-path-to-node=\"4,3,0\" data-index-in-node=\"292\">+354 420-1212<\/b> y menciones Camper Islandia para obtener una tarifa fija de socio.  <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_5 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">^<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">\u00bfC\u00f3mo me preparo para mi viaje a Islandia?<\/h4><div class=\"et_pb_blurb_description\"><p>Gracias por elegir Camper Iceland. Sus vacaciones en Islandia est\u00e1n llegando pronto, y nos gustar\u00eda prepararle tanto como sea posible antes de su viaje a Islandia.  <a href=\"https:\/\/www.camper.is\/es\/vegvisir-wayfinder-para-viajeros\/\">Leer m\u00e1s aqu\u00ed..<\/a><\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_6 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">^<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">\u00bfTiene una opci\u00f3n de pre-check-in?<\/h4><div class=\"et_pb_blurb_description\"><p>De hecho, lo hacemos y puede ahorrar hasta 30 minutos al registrarse. As\u00ed es como funciona, <a href=\"https:\/\/www.camper.is\/es\/vegvisir-wayfinder-para-viajeros\/registrar-tutorial-de-quiosco\/\">haga clic aqu\u00ed...<\/a> <\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_12 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_7 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">^<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">\u00bfHay alg\u00fan alojamiento cerca de la estaci\u00f3n de alquiler?<\/h4><div class=\"et_pb_blurb_description\"><p>En Keflavik hay varios hoteles y pensiones.  <\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_8 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">^<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">\u00bfC\u00f3mo llego a la estaci\u00f3n de alquiler una vez que he aterrizado en Islandia?<\/h4><div class=\"et_pb_blurb_description\"><p>Te explicamos por d\u00f3nde entras a nuestro pa\u00eds y c\u00f3mo puedes llegar a nuestra estaci\u00f3n de alquiler en nuestro<a href=\"https:\/\/www.camper.is\/es\/vegvisir-wayfinder-para-viajeros\/\"> p\u00e1gina del buscador de caminos<\/a><\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_9 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">^<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">\u00bfC\u00f3mo funciona el procedimiento de recogida?<\/h4><div class=\"et_pb_blurb_description\"><p>\u00bfEst\u00e1 interesado en nuestra sinstrucci\u00f3n sobre nuestros veh\u00edculos? Proporcionamos informaci\u00f3n y consejos y trucos \u00fatiles.  <a href=\"https:\/\/www.camper.is\/es\/vegvisir-wayfinder-para-viajeros\/\">Haga clic aqu\u00ed para obtener m\u00e1s informaci\u00f3n sobre ellos...<\/a><\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_10 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">^<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">\u00bfD\u00f3nde puedo ir de compras una vez que tenga mi veh\u00edculo?<\/h4><div class=\"et_pb_blurb_description\"><p>Hemos reunido informaci\u00f3n \u00fatil sobre los supermercados cercanos. <a href=\"https:\/\/www.camper.is\/es\/vegvisir-wayfinder-para-viajeros\/\">Haga clic aqu\u00ed para leer m\u00e1s...<\/a><\/p>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_11 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">^<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">\u00bfY si algo sale mal durante el viaje?<\/h4><div class=\"et_pb_blurb_description\"><p>Camper Islandia tiene la instrucci\u00f3n m\u00e1s avanzada y la experiencia de disparo de problemas en Islandia. Ser el alquiler de Camper m\u00e1s antiguo para proporcionar instrucci\u00f3n en vivo, videos de instrucci\u00f3n y l\u00ednea de apoyo.  <a href=\"https:\/\/www.camper.is\/es\/vegvisir-wayfinder-para-viajeros\/\">Haga clic aqu\u00ed para leer m\u00e1s...<\/a><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_2 et_pb_section et_section_regular et_block_section section_has_divider et_pb_top_divider\"><div class=\"et_pb_top_inside_divider et-no-transition\"><\/div>\n<div class=\"et_pb_row_8 et_pb_row et_block_row\">\n<div class=\"et_pb_column_13 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_dark et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>Nuestra Estaci\u00f3n de Alquiler<br \/>+354 860 1006<\/h2>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_9 et_pb_row et_block_row\">\n<div class=\"et_pb_column_14 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_12 et_pb_blurb et_pb_bg_layout_dark et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue076<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">info@camper.is<\/h4><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_15 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_13 et_pb_blurb et_pb_bg_layout_dark et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue090<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">+354 860 1006<\/h4><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_16 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_14 et_pb_blurb et_pb_bg_layout_dark et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><a href=\"https:\/\/goo.gl\/maps\/paTFJG2BPsNJ6i3y6\" target=\"_blank\" rel=\"noopener\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue081<\/span><\/span><\/a><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\"><a href=\"https:\/\/goo.gl\/maps\/paTFJG2BPsNJ6i3y6\" target=\"_blank\" rel=\"noopener\">Klettatr\u00f6\u00f0 15 | IS-262 KEFLAVIK<\/a><\/h4><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_10 et_pb_row et_block_row\">\n<div class=\"et_pb_column_17 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module\" href=\"https:\/\/web.rentalcarmanager.com\/api32\/Camper-Iceland\/\" target=\"_blank\" rel=\"noopener\">Reserve un coche en l\u00ednea<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_section_3 et_pb_section et_section_regular et_block_section section_has_divider et_pb_bottom_divider\">\n<div class=\"et_pb_row_11 et_pb_row et_block_row et_pb_row_fullwidth\">\n<div class=\"et_pb_column_18 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_15 et_pb_blurb et_pb_bg_layout_dark et_pb_text_align_center et_pb_blurb_position_top et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><a href=\"https:\/\/web.rentalcarmanager.com\/api32\/Camper-Iceland\/Step2\" target=\"_blank\" rel=\"noopener\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue030<\/span><\/span><\/a><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\"><a href=\"https:\/\/web.rentalcarmanager.com\/api32\/Camper-Iceland\/Step2\" target=\"_blank\" rel=\"noopener\">RESERVA en l\u00ednea<\/a><\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"https:\/\/web.rentalcarmanager.com\/api32\/Camper-Iceland\/Step2\" target=\"_blank\" rel=\"noopener\">RESERVAR AHORA<\/a><\/div>\n<\/div>\n\n<div class=\"et_pb_column_19 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_16 et_pb_blurb et_pb_bg_layout_dark et_pb_text_align_center et_pb_blurb_position_top et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image et_animated\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue01d<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Estaci\u00f3n de alquiler<\/h4><div class=\"et_pb_blurb_description\"><p><strong>Camper Islandia<\/strong><br \/>K L E T TATR\u00d6\u00d0 15<br \/>IS-262 Keflavik <br \/>ISLANDIA<br \/><a href=\"mailto:info@camper.is\" target=\"_blank\" rel=\"noopener noreferrer\">info@camper.is<\/a><br \/>IS<span>:+354 860 1006 <\/span> <\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div><span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":34167,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-31556","page","type-page","status-publish","hentry"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.camper.is\/es\/wp-json\/wp\/v2\/pages\/31556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.camper.is\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.camper.is\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.camper.is\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.camper.is\/es\/wp-json\/wp\/v2\/comments?post=31556"}],"version-history":[{"count":0,"href":"https:\/\/www.camper.is\/es\/wp-json\/wp\/v2\/pages\/31556\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.camper.is\/es\/wp-json\/wp\/v2\/pages\/34167"}],"wp:attachment":[{"href":"https:\/\/www.camper.is\/es\/wp-json\/wp\/v2\/media?parent=31556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}